{"id":7724,"date":"2020-08-13T15:21:00","date_gmt":"2020-08-13T13:21:00","guid":{"rendered":"https:\/\/gelassen-vital.at\/blog\/?p=7724"},"modified":"2023-08-30T21:19:00","modified_gmt":"2023-08-30T19:19:00","slug":"warum-tcm-fruehstueck-3-fruehstuecksrezepte","status":"publish","type":"post","link":"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/","title":{"rendered":"3 TCM Fr\u00fchst\u00fccksrezepte und warum ein Fr\u00fchst\u00fcck nach TCM gelassen und vital h\u00e4lt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sie sagen: &#8220;Wenn ich nach TCM mein Fr\u00fchst\u00fccksrezept zubereitet und in Ruhe gegessen habe, wirft mich der Alltagstrubel am restlichen Tag nicht mehr so leicht aus der Bahn.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch das <a href=\"https:\/\/amzn.to\/3DRKBLy\" target=\"_blank\" rel=\"noopener\">Wissen aus der Intergrativen Ern\u00e4hrung (mehr <\/a><a href=\"https:\/\/amzn.to\/3DRKBLy\" rel=\"sponsored noopener\" target=\"_blank\">dazu<\/a><a href=\"https:\/\/amzn.to\/3DRKBLy\" target=\"_blank\" rel=\"noopener\"> im Buch zum Nachlesen)<\/a> &#8211; die TCM Ern\u00e4hrung und westlicher Ern\u00e4hrungswissenschaft vereint &#8211; halten meine TCM Fr\u00fchst\u00fccksrezepte lange satt. Wenn du In diesem Blogartikel zeige ich dir, wie ein gekochtes Fr\u00fchst\u00fcck nach TCM-Prinzipien dich gelassen und vital starten l\u00e4sst. Ich stelle dir nicht nur die Vorteile vor, sondern teilen auch drei leckere TCM Fr\u00fchst\u00fccksrezepte, die dein Wohlbefinden f\u00f6rdern werden. Also, nimm dir eine Tasse Tee und lass uns eintauchen!<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#Warum_ein_gekochtes_Fruehstueck_nach_TCM\" >Warum ein gekochtes Fr\u00fchst\u00fcck nach TCM?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#1_TCM_Fruehstuecksrezept_Reisgericht\" >1# TCM Fr\u00fchst\u00fccksrezept: Reisgericht<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#2_TCM_Fruehstuecksrezept_Eiergericht\" >2# TCM Fr\u00fchst\u00fccksrezept: Eiergericht<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#3_TCM_Fruehstuecksrezept_einfacher_Haferbrei\" >3# TCM Fr\u00fchst\u00fccksrezept: einfacher Haferbrei<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#Warum_ist_das_Fruehstueck_in_der_TCM_so_wichtig_fuer_die_nachhaltige_Gesundheit\" >Warum ist das Fr\u00fchst\u00fcck in der TCM so wichtig f\u00fcr die nachhaltige Gesundheit?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#Welche_Zubereitungsmethode_ist_typisch_fuer_ein_Fruehstueckrezept_nach_TCM\" >Welche Zubereitungsmethode ist typisch f\u00fcr ein Fr\u00fchst\u00fcckrezept nach TCM?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#Welche_Grundsaetze_sind_beim_Fruehstueck_nach_TCM_zu_beachten\" >Welche Grunds\u00e4tze sind beim Fr\u00fchst\u00fcck nach TCM zu beachten?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/gelassen-vital.at\/blog\/warum-tcm-fruehstueck-3-fruehstuecksrezepte\/#Wichtig_noch_zum_Abschluss\" >Wichtig noch zum Abschluss<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"warum-ein-gekochtes-fruehstueck-nach-tcm\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Warum_ein_gekochtes_Fruehstueck_nach_TCM\"><\/span><strong>Warum ein gekochtes Fr\u00fchst\u00fcck nach TCM?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Stell dir vor, dein K\u00f6rper ist ein Orchester, und jedes Organ spielt eine entscheidende Rolle in deinem t\u00e4glichen Konzert des Lebens. Die TCM lehrt uns, dass ein ausgewogenes Fr\u00fchst\u00fcck der richtige Auftakt f\u00fcr dieses Konzert ist. Ein gekochtes Fr\u00fchst\u00fcck hilft deinem K\u00f6rper, sich sanft auf den Tag vorzubereiten. Hier sind einige Gr\u00fcnde, warum du diese morgendliche Praxis in Erw\u00e4gung ziehen solltest:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Energieausgleich:<\/strong> Ein gekochtes Fr\u00fchst\u00fcck wirkt wie ein Energieschub f\u00fcr deinen K\u00f6rper. Nach einer Nacht des Fastens ben\u00f6tigt dein Organismus N\u00e4hrstoffe, um wieder in Schwung zu kommen. Ein gekochtes Fr\u00fchst\u00fcck, basierend auf TCM-Prinzipien, gleicht deine Energiereserven aus und schenkt dir die n\u00f6tige Energie f\u00fcr den Tag.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Harmonisierung der Organe:<\/strong> In der TCM hat jedes Organ seine eigene Zeit, in der es am besten arbeitet. Ein gekochtes Fr\u00fchst\u00fcck zur richtigen Zeit kann dazu beitragen, dass deine Verdauungsorgane effizienter arbeiten und sich harmonisieren. Dadurch startest du den Tag mit einem ausgeglichenen Gef\u00fchl.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. St\u00e4rkung des Stoffwechsels:<\/strong> Ein gekochtes Fr\u00fchst\u00fcck f\u00f6rdert die Verdauung und regt den Stoffwechsel an. Dies hilft nicht nur bei der Aufnahme von N\u00e4hrstoffen, sondern unterst\u00fctzt auch die Entgiftung und Ausscheidung von Abfallstoffen aus deinem K\u00f6rper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Konzentration und Klarheit:<\/strong> Die richtigen Zutaten in deinem Fr\u00fchst\u00fcck k\u00f6nnen deine Konzentration und geistige Klarheit verbessern. Du wirst dich fokussierter f\u00fchlen und besser auf Aufgaben reagieren k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. Langanhaltende S\u00e4ttigung:<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein gekochtes Fr\u00fchst\u00fcck h\u00e4lt dich l\u00e4nger satt als viele andere Optionen. Das verhindert Hei\u00dfhungerattacken im Laufe des Tages und unterst\u00fctzt dich dabei, ges\u00fcndere Essgewohnheiten zu entwickeln.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TCM <strong>Fr\u00fchst\u00fccksrezepte<\/strong> m\u00fcssen nicht kompliziert gekocht werden. Einfache Zutaten. Einfacher f\u00fcr den Magen-Darm-Trakt. F\u00fcr die eine oder andere m\u00f6gen diese TCM Fr\u00fchst\u00fccksrezepte zu simple sein oder zu einseitig. Denen kann ich mein  online Kochkurs &#8220;Fr\u00fchst\u00fcckPOWER nach TCM&#8221; von Herzen empfehlen. 21 TCM Fr\u00fchst\u00fccksrezepte beschreibe ich im eKochbuch und ich erkl\u00e4re auch einige im Video. <a href=\"https:\/\/gelassen-vital.at\/blog\/nach-tcm-kochen-5-live-online-kochkurse\/\">Schau gern vorbei auf diese Seite um einen \u00dcberblick \u00fcber alle online Kochkurse zu gewinnen.  <\/a><\/p>\n\n\n\n<h2 id=\"1-tcm-fruehstuecksrezept-reisgericht\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_TCM_Fruehstuecksrezept_Reisgericht\"><\/span>1# TCM Fr\u00fchst\u00fccksrezept: Reisgericht<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reisbrei mit Obst<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein einfaches und dennoch kraftvolles TCM Fr\u00fchst\u00fccksrezept ist der Reisbrei mit Obst. Reisbrei ist leicht verdaulich und beruhigt den Magen. Hier ist, wie du ihn zubereitest:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zutaten f\u00fcr eine Person:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bd Tasse Jasminreis<\/li>\n\n\n\n<li>2 Tassen Wasser<\/li>\n\n\n\n<li>Eine Prise Salz<\/li>\n\n\n\n<li>Dein Lieblingsobst (z. B. \u00c4pfel, Birnen oder Beeren)<\/li>\n\n\n\n<li>Ein Teel\u00f6ffel Honig oder Ahornsirup (optional)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anleitung:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Den Reis gr\u00fcndlich waschen.<\/li>\n\n\n\n<li>Reis, Wasser und Salz in einen Topf geben und zum Kochen bringen.<\/li>\n\n\n\n<li>Die Hitze reduzieren und den Reis k\u00f6cheln lassen, bis er weich und breiig ist (ca. 15-20 Minuten), gelegentlich umr\u00fchren.<\/li>\n\n\n\n<li>Den Reisbrei in eine Sch\u00fcssel geben, mit Obst garnieren und bei Bedarf mit Honig oder Ahornsirup s\u00fc\u00dfen.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:41% auto\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--800x600.png\" alt=\"\" class=\"wp-image-5900 size-full\" srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--800x600.png 800w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--300x225.png 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--768x576.png 768w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--330x248.png 330w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM--1000x750.png 1000w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/die-antiken-Gelehrten-aus-der-TCM-.png 1024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<blockquote class=\"wp-block-quote is-style-default has-white-background-color has-background is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:30px\">&#8220;Der Weise nimmt Nahrung als Medizin, w\u00e4hrend der Unweise Medizin als Nahrung nimmt.&#8221; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:30px\">(\u9ec4\u5e1d\u5185\u7ecf &#8211; Hu\u00e1ng D\u00ec N\u00e8i J\u012bng)<\/p>\n<cite>Chinesische Weisheit<\/cite><\/blockquote>\n<\/div><\/div>\n\n\n\n<h2 id=\"2-tcm-fruehstuecksrezept-eiergericht\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_TCM_Fruehstuecksrezept_Eiergericht\"><\/span>2# TCM Fr\u00fchst\u00fccksrezept: Eiergericht<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center is-style-default\" style=\"grid-template-columns:auto 65%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#000000\"><strong>Eiergerichte in jeder Form<\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"571\" height=\"400\" data-src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2023\/08\/Fruehstueck-nach-TCM-Gemuesesuppe-mit-Ei.png\" alt=\"\" class=\"wp-image-7791 size-full lazyload\" data-srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2023\/08\/Fruehstueck-nach-TCM-Gemuesesuppe-mit-Ei.png 571w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2023\/08\/Fruehstueck-nach-TCM-Gemuesesuppe-mit-Ei-300x210.png 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2023\/08\/Fruehstueck-nach-TCM-Gemuesesuppe-mit-Ei-330x231.png 330w\" data-sizes=\"(max-width: 571px) 100vw, 571px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 571px; --smush-placeholder-aspect-ratio: 571\/400;\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gem\u00fcsesuppe mit Ei<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese herzhafte Gem\u00fcsesuppe mit Ei ist perfekt f\u00fcr einen proteinreichen Start in den Tag. Sie harmonisiert nach TCM die Verdauungsorgane und schenkt dir eine warme Energiequelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zutaten:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2 Tassen Gem\u00fcsebr\u00fche bzw. Wasser mit Suppenw\u00fcrze (Erde-Element) bzw. (Wasser-Element)<\/li>\n\n\n\n<li>Verschiedenes Gem\u00fcse deiner Wahl (Karotten, Zucchini, Kartoffeln, etc.) (Erde-Element)<\/li>\n\n\n\n<li>1 Ei (Erde-Element)<\/li>\n\n\n\n<li>Ein Teel\u00f6ffel Ingwer, fein gehackt (Metall-Element)<\/li>\n\n\n\n<li>Ein Teel\u00f6ffel Sesam\u00f6l (Erde-Element)<\/li>\n\n\n\n<li>Salz oder Sojaso\u00dfe nach Geschmack (Wasser-Element)<\/li>\n\n\n\n<li>Fr\u00fchlingszwiebeln oder Koriander zum Garnieren (Metall-Element)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anleitung:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ingwer und Sesam\u00f6l in einem Suppentopf erhitzen.<\/li>\n\n\n\n<li>klein geschnittenes Gem\u00fcse hinzuf\u00fcgen, umr\u00fchren.<\/li>\n\n\n\n<li>Mit Gem\u00fcsebr\u00fche aufgie\u00dfen und einmal aufkochen lassen.<\/li>\n\n\n\n<li>Dann auf mittlere Hitze zur\u00fcckschalten und noch cirka 10 Minuten k\u00f6cheln lassen, bis das Gem\u00fcse weich ist.<\/li>\n\n\n\n<li>Ein Ei in einem Kaffeeh\u00e4ferl verquirlen und langsam in die kochende Suppe r\u00fchren, bis es stockt.<\/li>\n\n\n\n<li>Mit Salz oder Sojaso\u00dfe abschmecken und in eine Sch\u00fcssel geben. Mit feingeschnittenen Fr\u00fchlingszwiebeln oder Koriander garnieren.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Der Gedanke eine Suppe zum Fr\u00fchst\u00fcck zu essen, ist f\u00fcr die meisten gew\u00f6hnungsbed\u00fcrftig. Das gebe ich zu. Das kenne ich von mir, als ich im Jahre 2016 mit dem Kochen nach TCM damit begonnen habe. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die klassischen Eiergerichte wie weiches Ei, Spiegelei mit Speck oder f\u00fcr Vegetarier mit gebratenen Zucchini oder die typische Eierspeis&#8217; sind ebenso perfekt f\u00fcr den gelassenen, vitalen Start in den Tag. Die TCM f\u00fcr dazu noch die passenden Gew\u00fcrze empfehlen und das Brot dazu antoasten. Warum das Brot antoasten? Das erz\u00e4hle ich dir weiter unten bei den h\u00e4ufig gestellten Fragen zum Fr\u00fchst\u00fcck nach TCM. <\/p>\n\n\n\n<h2 id=\"3-tcm-fruehstuecksrezept-einfacher-haferbrei\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_TCM_Fruehstuecksrezept_einfacher_Haferbrei\"><\/span>3# TCM Fr\u00fchst\u00fccksrezept: einfacher Haferbrei<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Haferbrei mit N\u00fcssen und Beeren<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Klassiker ist das TCM Fr\u00fchst\u00fcck Haferporridge nach den 5 Elementen gekocht. Trotz seiner einfachen Zutaten ist er reich an Ballaststoffen und Eiwei\u00df, was dich lange satt h\u00e4lt und Energie liefert. Deine Konzentration f\u00f6rdert und du geistig klar im Kopf bleibst f\u00fcr einen langen, gelassenen und vitalen Tag also.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zutaten f\u00fcr 1 Portion:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bd Tasse Haferflocken (Erde-Element)<\/li>\n\n\n\n<li>1 Tasse Wasser oder Mandelmilch (Erde-Element)<\/li>\n\n\n\n<li>Eine Handvoll gemischte N\u00fcsse (Mandeln, Waln\u00fcsse, etc.) (Erde-Element)<\/li>\n\n\n\n<li>Eine Handvoll Beeren (Heidelbeeren, Himbeeren, Rosinen etc.) (Erde-Element)<\/li>\n\n\n\n<li>Ein Teel\u00f6ffel Honig oder Ahornsirup (optional) (Erde-Element)<\/li>\n\n\n\n<li>1 Prise Zimt (Feuer-Element)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anleitung:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Haferflocken und Wasser bzw. Mandelmilch, Rosinen und Zimt in einem Topf erhitzen.<\/li>\n\n\n\n<li>Unter gelegentlichem R\u00fchren leicht k\u00f6cheln lassen, bis der Brei eingedickt ist.<\/li>\n\n\n\n<li>Die N\u00fcsse grob hacken und in den Brei r\u00fchren.<\/li>\n\n\n\n<li>Den Haferbrei in eine Sch\u00fcssel geben, mit Beeren garnieren und bei Bedarf mit Honig oder Ahornsirup s\u00fc\u00dfen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vielleicht denkst du jetzt, dass diese 2 Fr\u00fchst\u00fccksbreirezepte fad schmecken k\u00f6nnten. Wie du sehen kannst, sind haupts\u00e4chlich Zutaten aus dem Erde-Element enthalten. Durch die Zugabe von Gew\u00fcrzen und naturreinen Aromastoffen kannst du es nach deinen Vorlieben individuell zubereiten. <a href=\"https:\/\/gelassen-vital.at\/blog\/7-lieblinge-gewuerze-suessspeisen-nach-tcm\">Meine 7 Lieblingsgew\u00fcrze habe ich hier ausf\u00fchrlicher zusammengefasst und in ihre psychosomatischen Botschaft erkl\u00e4rt. <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Statt Zimt nimm gerne Vanille.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oder gib geriebene, getrocknete Orangenschale dazu in den Reisbrei und ein wenig Kardamompulver. Erst die Gew\u00fcrze geben dem Fr\u00fchst\u00fccksbrei energetische Wirkrichtungen. Denn die s\u00fc\u00dfliche Geschmackskomponente der Erde-Elemente-Zutaten liegt wie Erde einfach rum und bewegt sich nicht weiter. Die Milz-Energie braucht aber die Wirkrichtung der Bewegung und des Nach-unten-leitens in Richtung Darmschlauch.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb sagt die TCM &#8211; Ern\u00e4hrungslehre der leicht scharfe Geschmack vom Kardamom l\u00e4sst die Zutaten aus dem Erde-Element in energetischer Richtung zum Darm nach unten bewegen sowie nach au\u00dfen in Richtung Haut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zimt hingegen hat nur eine nach-unten-Bewegung zum Darm. Seine thermische Wirkung f\u00fcr den menschlichen Organismus ist die erw\u00e4rmende Kraft (das Yang). Welche nicht nur die Mitte erw\u00e4rmt, sondern noch tiefer wirkt bis in die Nieren. Das nennt man im Fachjargon: das Nieren Yang st\u00fctzen. <\/p>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1693417859801\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Warum_ist_das_Fruehstueck_in_der_TCM_so_wichtig_fuer_die_nachhaltige_Gesundheit\"><\/span><strong>Warum ist das Fr\u00fchst\u00fcck in der TCM so wichtig f\u00fcr die nachhaltige Gesundheit?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>In der Traditionellen Chinesischen Medizin (TCM) hat das Fr\u00fchst\u00fcck eine zentrale Bedeutung f\u00fcr die F\u00f6rderung der nachhaltigen Gesundheit. Es wird nicht nur als eine Mahlzeit angesehen, die den K\u00f6rper mit Energie versorgt, sondern auch als eine M\u00f6glichkeit, den Energiefluss im K\u00f6rper zu harmonisieren und das Gleichgewicht von Yin und Yang aufrechtzuerhalten.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1693417874744\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Welche_Zubereitungsmethode_ist_typisch_fuer_ein_Fruehstueckrezept_nach_TCM\"><\/span><strong>Welche Zubereitungsmethode ist typisch f\u00fcr ein Fr\u00fchst\u00fcckrezept nach TCM?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Wir k\u00f6nnen die Speisen an einen der 4 Konstitutionstypen anpassen und f\u00fcr unser Yin-Yang-Gleichgewicht f\u00fcr das k\u00f6rperliche und geistige Wohlbefinden optimieren. Frische und nat\u00fcrliche Zutaten geben das Qi in die Speise und somit einverleiben wir quasi diese Lebensenergie. <\/p>\n<p><strong>Wir k\u00f6nnen Speisen yangig oder yining zubereiten. <\/strong><br \/>Bist du ein Morgenmuffel und sehr tr\u00e4ge beim in die G\u00e4nge kommen am Morgen, brauchst du mehr Yang in deinen Organsystemen. Meist hast du dann auch oft kalte H\u00e4nde und F\u00fcsse und solltest zum Beispiel bewusst Zimt oder Gew\u00fcrznelke &#8211; beide sind thermisch hei\u00df in der Wirkung &#8211; in deine s\u00fc\u00dflichen Fr\u00fchst\u00fccksrezepte einbauen. Das w\u00e4re zum Beispiel eine typische Ab\u00e4nderung der Ern\u00e4hrung. Eine kleine Ma\u00dfnahme &#8211; best\u00e4ndig und t\u00e4glich f\u00fcr wenige Monate &#8211; angewandt, was diese <strong>yangige Zubereitungsmethode <\/strong>auf l\u00e4ngere Sicht Gutes bewirken kann. <\/p>\n<p>Bist du eine Person, die immer auf Achse ist (= yangig) und nur im Urlaub Ruhe (= yinig) gibt, dann solltest du um deine Yin-Yang-Balance zu im Gleichgewicht zu halten, <strong>yinige Zubereitungsmethoden <\/strong>w\u00e4hlen. Ich empfehle ihr eine saftigere Zubereitungsweise beim Fr\u00fchst\u00fccksbrei. So bald dein Yin-Yang-Gleichgewicht in deiner Verdauungs-Mitte ausgeglichen ist, kannst du auch ab und zu &#8216;normale&#8217; Fr\u00fchst\u00fcckkost essen. Wie zum Beispiel das typische B\u00e4ckerfr\u00fchst\u00fcck am Sonntag.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1693417938879\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Welche_Grundsaetze_sind_beim_Fruehstueck_nach_TCM_zu_beachten\"><\/span><strong>Welche Grunds\u00e4tze sind beim Fr\u00fchst\u00fcck nach TCM zu beachten?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Es sind 3 Grunds\u00e4tze f\u00fcr das Zubereiten vom TCM Fr\u00fchst\u00fccksrezept: <br \/>a) Nimm gute Qualit\u00e4t von Zutaten, am besten ausgereiftes Obst und Gem\u00fcse aus Bio-Anbau. Diese haben einen hohen Qi-Gehalt. <\/p>\n<p>b) Verwende mindestens 2 Gew\u00fcrze oder Zutaten, die das Qi der Speise bewegen. Dazu schau auf die Lebensmitteltabelle. Dort findest du die geschmackliche Zuordnung und die thermische Wirkung in 5 Spalten abgebildet.<\/p>\n<p>c) Koche Mitte-st\u00e4rkend, damit du deinen Konstitutionstypen nach TCM im Gleichgewicht halten kannst. Auf lange Sicht ist es f\u00fcr die Verdauungs-Mitte besser, gekochte Speisen zu essen. So hat der K\u00f6rper einen geringeren Energieaufwand die rohen Pflanzen wie Karotten oder Salat zu zersetzen. Diese Energie kann er f\u00fcr die restlichen Aufgabenstellungen am Tag nutzen.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 id=\"wichtig-noch-zum-abschluss\" class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wichtig_noch_zum_Abschluss\"><\/span>Wichtig noch zum Abschluss<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Denke immer daran, auf dein eigenes Gef\u00fchl zu h\u00f6ren. Ein warmes Gef\u00fchl im Bauch ist ein gutes Zeichen, dass das Fr\u00fchst\u00fcck f\u00fcr dich richtig ist. Bl\u00e4hungen, Aufsto\u00dfen oder V\u00f6llegef\u00fchl deuten darauf hin, dass bestimmte Nahrungsmittel dir nicht guttun. \u00dcbernimm&#8217; Verantwortung f\u00fcr dich und w\u00e4hle ein Fr\u00fchst\u00fcck, das dich gut f\u00fchlen l\u00e4sst!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denk dran, du bist einzigartig, und dein Fr\u00fchst\u00fcck sollte zu dir passen. Mit der richtigen Wahl am Morgen wirst du nicht nur energiegeladen in den Tag starten, sondern auch langfristig von den positiven Effekten profitieren. Also, nimm dir Zeit f\u00fcr ein typgerechtes Powerfr\u00fchst\u00fcck nach TCM und erlebe die Ver\u00e4nderung!<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein gesundes Fr\u00fchst\u00fcck nach TCM bringt eindeutig mehr Ruhe und Energie f\u00fcr den Tag. Sag&#8217; nicht nur ich oder die TCM Gesundheitsphilosopie. Das sp\u00fcren meine Klient:innen eindeutig nach 3 Wochen. Sie f\u00fchlen sich ausgeglichener und gelassener. <\/p>\n","protected":false},"author":1,"featured_media":7792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"foodblogkitchen_pinterest_image_id":0,"foodblogkitchen_pinterest_image_url":"","rating_1_votes":0,"rating_2_votes":0,"rating_3_votes":0,"rating_4_votes":0,"rating_5_votes":0,"rating_count":0,"average_rating":0,"footnotes":""},"categories":[1],"tags":[],"post_folder":[72],"class_list":["post-7724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-im-alltag"],"_links":{"self":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/7724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/comments?post=7724"}],"version-history":[{"count":46,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/7724\/revisions"}],"predecessor-version":[{"id":8162,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/7724\/revisions\/8162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/media\/7792"}],"wp:attachment":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/media?parent=7724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/categories?post=7724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/tags?post=7724"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/post_folder?post=7724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}