{"id":6619,"date":"2020-11-29T11:01:00","date_gmt":"2020-11-29T10:01:00","guid":{"rendered":"https:\/\/gelassen-vital.at\/blog\/?p=6619"},"modified":"2022-12-08T20:17:31","modified_gmt":"2022-12-08T19:17:31","slug":"maroni-creme-dessert-mit-datteln","status":"publish","type":"post","link":"https:\/\/gelassen-vital.at\/blog\/maroni-creme-dessert-mit-datteln\/","title":{"rendered":"Maroni Creme Dessert nach TCM mit Datteln f\u00fcr starke Nerven"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Maroni Creme mit Datteln ist eine super schnelles Dessert, das sich wohlig im Bauch anf\u00fchlt, die H\u00fcften nicht belastet und sogar deine Nervenkraft aufbaut. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maroni oder auch Kastanien genannt, sind f\u00fcr die meisten <strong>sehr bek\u00f6mmlich. Besonders Menschen mit einer ausgepowerten Verdauungsmitte merken den wohliges Gef\u00fchl im Bauch. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wissenswertes \u00fcber die Kastanie oder Maroni genannt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bevor die Kartoffel entdeckt wurde, galten die auch als <strong>Ess- oder Edelkastanien (Castanea sativa) bezeichneten Maroni als Hauptnahrungsmittel<\/strong> in den Bergregionen S\u00fcdeuropas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie galten fr\u00fcher als Arme-Leute-Essen. Heute sind die Maroni, die den K\u00f6rper von innen w\u00e4rmen und st\u00e4rken, in der Allerheiligenzeit <strong>Anfang November und in der Weihnachtszeit<\/strong> nicht mehr wegzudenken.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vital-und-inhaltsstoffe-fuer-starke-nerven-und-eine-starke-verdauungsmitte\">Vital- und Inhaltsstoffe f\u00fcr starke Nerven und eine starke Verdauungsmitte<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wer kennt ihn nicht \u2013 den allj\u00e4hrlichen Weihnachtsstress. Die <strong>Nerven st\u00e4rkenden B-Vitamine<\/strong> sind in Maronis aber Gott sei Dank in reichlicher Menge vorhanden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere wertvolle <strong>Mineralstoffe sind Kalium und Phosphor, die Knochen und Z\u00e4hne st\u00e4rken.<\/strong> Aber auch Vitamin C, das eine Rolle bei der Immunabwehr spielt, ist darin zu finden. Au\u00dferdem machen die Maroni schnell und lang anhaltend satt, da sie einen hohen St\u00e4rke-Gehalt aufweisen. Der Fettanteil ist gegen\u00fcber allen anderen N\u00fcssen mit 2% verschwindend gering. <strong>Also steht dieser Nascherei nichts im Wege.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maronis eignen sich auch vorz\u00fcglich als <strong>Einlage f\u00fcr Suppen oder in Kombination mit Rotkraut oder Wild.<\/strong> <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"die-anwendungsgebiete-der-maroni-in-der-tcm\">Die Anwendungsgebiete der Maroni in der TCM<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u262f\ufe0e M\u00fcdigkeit, Abgeschlagenheit, Energiemangel, Ersch\u00f6pfung<br>\u262f\ufe0e An\u00e4mie, Blutmangel<br>\u262f\ufe0e Untergewicht, Auszehrung<br>\u262f\ufe0e k\u00f6rperliche Belastung und im Wachstum<br>\u262f\ufe0e weicher Stuhl, Durchfall<br>\u262f\ufe0e Muskelschw\u00e4che, Sehnenschw\u00e4che<br>\u262f\ufe0e Nervenschw\u00e4che<br>\u262f\ufe0e Milchbildungsmangel in der Stillzeit<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"die-wirkung-der-maroni-in-tcmfachjargon\">Die Wirkung der Maroni in TCM-Fachjargon<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tonisiert das Qi von der Verdauung und der Nieren, gut bei M\u00fcdigkeit, Abgeschlagenheit, Energielosigkeit, Auszehrung, im Wachstum, Stillzeit, Br\u00fcckenschw\u00e4che, zu welchem Stuhl, Darmflora St\u00f6rungen, Sehnen- und Muskelschw\u00e4che, Nervenfunktionsst\u00f6rung;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Baut harmonisiert das Yin, hilft bei Beinschw\u00e4che, Nervenschw\u00e4che, n\u00e4hrt das Gehirn, tonisiert das Yang ebenso wie die Essenz, reguliert Blutungen wie bei Nasen bluten, Darmblutung, bewegt Blut bei schmerzen, Quetschungen, Prellungen, tonisiert Blut gut bei Blutmangel, An\u00e4mie,&nbsp; transformiert Feuchtigkeit, gut bei erh\u00f6hten Rheuma, Arthrose, wirkt adstringierend gut bei Blutungen, Durchfall; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Achtung: im \u00dcberma\u00df oder roh gegessen erzeugen Maroni Bl\u00e4hungen und Nahrungsstau. Sind f\u00fcr Diabetiker geeignet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"was-kochen-mit-maroni-und-kastanien\">Was kochen mit Maroni und Kastanien?<\/h3>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"480\" data-id=\"3288\" src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/Kastanie-ein-Darmschmeichler-Lebensmittel.png\" alt=\"Maroni und Kastanien sind Darmschmeichler\" class=\"wp-image-3288\" srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/Kastanie-ein-Darmschmeichler-Lebensmittel.png 480w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/Kastanie-ein-Darmschmeichler-Lebensmittel-300x300.png 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/Kastanie-ein-Darmschmeichler-Lebensmittel-150x150.png 150w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/Kastanie-ein-Darmschmeichler-Lebensmittel-330x330.png 330w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><figcaption class=\"wp-element-caption\">Maroni und Kastanien sind Darmschmeichler<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"720\" height=\"720\" data-id=\"1901\" data-src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Glasierte-Maroni-in-Sauce-zum-Braten.png\" alt=\"TCM Rezept Glasierte Maroni in Sauce zum Braten\" class=\"wp-image-1901 lazyload\" data-srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Glasierte-Maroni-in-Sauce-zum-Braten.png 720w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Glasierte-Maroni-in-Sauce-zum-Braten-300x300.png 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Glasierte-Maroni-in-Sauce-zum-Braten-150x150.png 150w\" data-sizes=\"(max-width: 720px) 100vw, 720px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 720px; --smush-placeholder-aspect-ratio: 720\/720;\" \/><figcaption class=\"wp-element-caption\">Glasierte Maroni in Sauce zum Bratfleisch<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"720\" height=\"720\" data-id=\"1915\" data-src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Maronicreme-it-besoffenen-Feigen.png\" alt=\"TCM Rezept Maronicreme mit besoffenen Feigen\" class=\"wp-image-1915 lazyload\" data-srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Maronicreme-it-besoffenen-Feigen.png 720w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Maronicreme-it-besoffenen-Feigen-300x300.png 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2021\/11\/TCM-Rezept-Maronicreme-it-besoffenen-Feigen-150x150.png 150w\" data-sizes=\"(max-width: 720px) 100vw, 720px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 720px; --smush-placeholder-aspect-ratio: 720\/720;\" \/><figcaption class=\"wp-element-caption\">Maronicreme mit besoffenen Feigen<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 id=\"die-datteln-im-pflanzenpowerportrait\" class=\"has-text-align-left wp-block-heading\">Die Datteln im PflanzenPOWERportrait<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Den Ursprung hat die Dattel in Afrika, wo sie auch heute noch exportiert wird. Aber auch im s\u00fcdlichen Mittelmeerraum, in Australien, im S\u00fcden der USA und in Mexiko werden Dattelpalmen inzwischen angebaut. Die auf weiblichen Palmen wachsenden Beerenfr\u00fcchte brauchen bis zu 10 Jahre f\u00fcr ihre Reifung. Das Fruchtfleisch erinnert geschmacklich an Honig und wird gerne zum S\u00fc\u00dfen von Backwaren verwendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In China gibt es den Spruch \u201eWenn der Himmel eine Dattel fallen l\u00e4sst, musst du deinen Mund \u00f6ffnen.\u201c Auch die Beduinen haben die Nahrhaftigkeit dieser Fr\u00fcchte erkannt. Sie nennen Datteln das \u201eBrot der W\u00fcste\u201c. Das Wort Dattel leitet sich vom griechischen \u201edaktylos\u201c ab und bedeutet \u201eFinger\u201c. Im arabischen Sprachraum hei\u00dft eine der besten Sorten \u201eDeglet Nour\u201c \u2013 was so viel hei\u00dft wie \u201eFinger des Lichts\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datteln sind vor allem als Unterst\u00fctzung bei Verdauungsproblemen sehr beliebt, da sie den Magen-Darm-Trakt nicht belasten. Sie haben einen hohen, aber gut verdaulichen Zuckeranteil sowie einen au\u00dferordentlich hohen Ballaststoffanteil, der sogar jene eines Vollkornbrotes \u00fcbertrifft. Au\u00dferdem sind sie reich an Kalium, Magnesium, Phosphor, Kupfer und Pantothens\u00e4ure, die f\u00fcr ein sch\u00f6nes Hautbild sorgt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei uns kennt man Datteln vor allem in ihrer getrockneten und mit Zucker und Sirup verarbeiteten Form. Auch im g\u00e4ngigen Lebensmittelhandel gibt&#8217;s Dattelsirup zu kaufen. Ich gebe ihn gerne in Kakao und dunklen Cremen zum S\u00fc\u00dfen dazu. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie sind aber in der Zeit zwischen Oktober und J\u00e4nner auch in frischer Form erh\u00e4ltlich. Beim Kauf frischer Datteln sollten Sie darauf achten, dass die Frucht zwar weich, aber keinesfalls matschig ist. Die weniger s\u00fc\u00dfen frischen Datteln muss man vor dem Verzehr enth\u00e4uten. Nach dem Sch\u00e4len sei jedem geraten, sich schnell die H\u00e4nde zu waschen, denn die braune Farbe geht sonst nur sehr schwer ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frische Datteln werden gerne in Obstsalate gemischt. Getrocknete Datteln k\u00f6nnen mit K\u00e4se oder Pasteten gef\u00fcllt werden. Oder mit Speck ummantelt herausgebraten serviert werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Vorweihnachtszeit beliebt sind s\u00fc\u00dfe F\u00fcllung mit N\u00fcssen, Marzipan oder Nougat. Fein gehackt k\u00f6nnen Datteln mit Rosinen passen sie gut in den weihnachtlichen Bratapfel. <\/p>\n\n\n<div class=\"foodblogkitchen-toolkit--block foodblogkitchen-toolkit--recipe-block  aligncenter\"\n  id=\"foodblogkitchen-toolkit--recipe\">\n  <section class=\"foodblogkitchen-toolkit--block--inner\">\n\n    <div class=\"foodblogkitchen-toolkit--recipe-block--title\">\n      <h2>Maroni Creme Dessert mit Datteln<\/h2>\n    <\/div>\n\n    <div class=\"foodblogkitchen-toolkit--recipe-block--intro\">\n      <div class=\"foodblogkitchen-toolkit--recipe-block--rating foodblogkitchen-toolkit--recipe-block--rating--small\">\n        <ol>\n          <li class=\"foodblogkitchen-toolkit--recipe-block--star selected\" data-rating=\"1\">1\n          <\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star selected\"\n            data-rating=\"2\">2<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star selected\"\n            data-rating=\"3\">3<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star selected\"\n            data-rating=\"4\">4<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star selected\"\n            data-rating=\"5\">5<\/li>\n        <\/ol>\n      <\/div>\n\n      <p>Maroni Creme mit Datteln ist eine gesundes, schnelles Dessert f\u00fcr die Nerven. Du wirst es lieben, wenn du oft zu S\u00fc\u00dfgusto am Nachmittag neigst.<\/p>\n\n      <span class=\"foodblogkitchen-toolkit--recipe-block--difficulty\">einfach<\/span>\n\n    <\/div>\n\n    <div class=\"foodblogkitchen-toolkit--recipe-block--thumbnail lazyload\"\n      style=\"background-image:inherit;\" title=\"Maroni Creme Dessert mit Datteln\" data-bg-image=\"url(&#039;https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/11\/Maroni-Creme-mit-Datteln-ein-leichtes-Dessert-330x267.png&#039;) !important\"><\/div>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--timings\">\n      <ul>\n        <li>\n          <header>Vorbereitungszeit:<\/header>\n          <span>8 Minuten<\/span>\n        <\/li>\n\n\n\n\n        <li>\n          <header>Gesamtzeit:<\/header>\n          <span>8 Minuten<\/span>\n        <\/li>\n      <\/ul>\n    <\/section>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--ingredients\">\n      <div class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Zutaten<\/h3>\n        <div class=\"foodblogkitchen-toolkit--recipe-block--servings-editor\">\n          <button type=\"button\" class=\"recipe-shrink-servings\">&#8211;<\/button>\n          <span disabled=\"disabled\">\n            <span class=\"recipe-servings\">2<\/span>\n            Portionen\n          <\/span>\n          <button type=\"button\" class=\"recipe-increase-servings\">+<\/button>\n        <\/div>\n      <\/div>\n      <table class=\"foodblogkitchen-toolkit--recipe-block--ingredients-table\" \n        data-recipe-yield=\"2\"  \n        data-recipe-yield-width=\"0\"  \n        data-recipe-yield-height=\"0\"  data-recipe-yield-unit=\"servings\">\n        <tbody>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item foodblogkitchen-toolkit--even\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"200\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"g\"\n            >200 g<\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">vorgegarte Maroni, <\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"50\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"\"\n            >50 <\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">&#8211; 100 g Datteln, <\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item foodblogkitchen-toolkit--even\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"125\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"ml\"\n            >125 ml<\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">Obers<\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"2\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"\"\n            >2 <\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">Prisen gemahlen Kardamom <\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item foodblogkitchen-toolkit--even\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"\"\n              data-recipe-format=\"\"\n              data-recipe-unit=\"\"\n            > <\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">etwas Wasser zum Einweichen der Datteln<\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"10\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"\"\n            >10 <\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">Himbeeren<\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item foodblogkitchen-toolkit--even\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"1\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"EL\"\n            >1 EL<\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">Kakaopulver nach Geschmack, <\/td>\n          <\/tr>\n          <tr\n            class=\"foodblogkitchen-toolkit--recipe-block--ingredients-item\">\n            <td\n              class=\"foodblogkitchen-toolkit--recipe-block--amount\"\n              data-recipe-amount=\"2\"\n              data-recipe-format=\"decimal\"\n              data-recipe-unit=\"\"\n            >2 <\/td>\n            <td class=\"foodblogkitchen-toolkit--recipe-block--ingredient\">Prisen Cylon Zimt<\/td>\n          <\/tr>\n        <\/tbody>\n      <\/table>\n    <\/section>\n\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--utensils\">\n      <div class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Utensilien<\/h3>\n      <\/div>\n      <ul class=\"foodblogkitchen-toolkit--recipe-block--utensils-list\">\n        <li>Hohen Gef\u00e4\u00df zum P\u00fcrieren, Stabmixer<\/li>\n      <\/ul>\n    <\/section>\n\n    <div class=\"foodblogkitchen-toolkit--recipe-block--preparation-steps\">\n      <div class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Zubereitung<\/h3>\n      <\/div>\n\n      <ol>\n        <li>Datteln klein schneiden. In einem Topf mit etwas Wasser kurz weichkochen. (Wenn du mehr Zeit hast, kannst du es in einem Gef\u00e4ss mit warmem Wasser 1 Stunde einweichen.)<\/li><li>Maroni und Gew\u00fcrze in einen hohen Beh\u00e4lter mit etwas Obers (oder vegan \/ Laktose frei: 2 EL Mandelmus p\u00fcrieren.<\/li><li>Danach die abgek\u00fchlten Datteln dazugeben und mit p\u00fcrieren.<\/li><li>Den geschlagenen Obers unterr\u00fchren und alles in Gl\u00e4ser oder Sch\u00fcsseln einf\u00fcllen.<br>Vorm Servieren mit frischem Obst wie Himbeeren und \/ oder Kakaopulver dekorieren und verfeinern.<\/li>\n      <\/ol>\n    <\/div>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--video\">\n      <header class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Video<\/h3>\n      <\/header>\n      <div class=\"foodblogkitchen-toolkit--recipe-block--video-wrapper\">\n        <iframe data-src=\"\/\/www.youtube-nocookie.com\/embed\/f7EjHned9O0\" frameborder=\"0\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe>\n      <\/div>\n    <\/section>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--notes\">\n      <header class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Notizen<\/h3>\n      <\/header>\n      <p>Kennst du schon die schnelle Kastaniesuppe nach TCM. Hier ist das Video und das Rezept dazu findest du hier: https:\/\/gelassen-vital.at\/blog\/tcm-rezept-kastaniensuppe-in-3-schritten\/ <\/p>\n    <\/section>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--user-rating\">\n      <header class=\"foodblogkitchen-toolkit--recipe-block--headline\">\n        <h3>Wie findest du das Rezept?<\/h3>\n      <\/header>\n      <div class=\"foodblogkitchen-toolkit--recipe-block--rating foodblogkitchen-toolkit--recipe-block--interactive\"\n        data-post-id=\"6619\" data-save-url=\"https:\/\/gelassen-vital.at\/blog\/wp-admin\/admin-ajax.php\" data-nonce=\"95600e57a1\">\n        <ol>\n          <li class=\"foodblogkitchen-toolkit--recipe-block--star\" data-rating=\"1\">1\n          <\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star\"\n            data-rating=\"2\">2<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star\"\n            data-rating=\"3\">3<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star\"\n            data-rating=\"4\">4<\/li>\n          <li\n            class=\"foodblogkitchen-toolkit--recipe-block--star\"\n            data-rating=\"5\">5<\/li>\n        <\/ol>\n      <\/div>\n    <\/section>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--save-and-share\">\n      <ul class=\"foodblogkitchen-toolkit--recipe-block--share-buttons\">\n        <li>\n          <button class=\"foodblogkitchen-toolkit--recipe-block--print-button\">Drucken<\/button>\n        <\/li>\n        <li>\n          <a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/?url&#x3D;https%3A%2F%2Fgelassen-vital.at%2Fblog%2Fwp-json%2Fwp%2Fv2%2Fposts%2F6619&amp;media&#x3D;https%3A%2F%2Fgelassen-vital.at%2Fblog%2Fwp-content%2Fuploads%2F2022%2F11%2FMaroni-Creme-mit-Datteln-ein-leichtes-Dessert.png&amp;description&#x3D;Maroni+Creme+mit+Datteln+ist+eine+gesundes%2C+schnelles+Dessert+f%C3%BCr+die+Nerven.+Du+wirst+es+lieben%2C+wenn+du+oft+zu+S%C3%BC%C3%9Fgusto+am+Nachmittag+neigst.\" target=\"_blank\"\n            class=\"foodblogkitchen-toolkit--recipe-block--share-on-pinterest\">Pin it<\/a>\n        <\/li>\n      <\/ul>\n    <\/section>\n\n    <section class=\"foodblogkitchen-toolkit--recipe-block--call-to-action\">\n      <div class=\"foodblogkitchen-toolkit--recipe-block--call-to-action--icon\"><\/div>\n      <div class=\"foodblogkitchen-toolkit--recipe-block--call-to-action--text\">\n        <h3>Du hast das Rezept ausprobiert?<\/h3>\n        <p>\n          Dann verlinke <a href=\"https:\/\/www.instagram.com\/Martina_vitalergy\/\" target=\"_blank\" rel=\"nofollow noopener\">@Martina_vitalergy<\/a> auf Instagram oder nutze den Hashtag <a href=\"https:\/\/www.instagram.com\/explore\/tags\/kochen-nach-TCM\/\" target=\"_blank\" rel=\"nofollow noopener\">#kochen-nach-TCM<\/a>.\n        <\/p>\n      <\/div>\n    <\/section>\n  <\/section>\n\n\n  <script>\n    var FoodblogkitchenToolkit = FoodblogkitchenToolkit || {};\n    FoodblogkitchenToolkit.config = {\n      ajaxUrl: 'https:\/\/gelassen-vital.at\/blog\/wp-admin\/admin-ajax.php',\n      nonce: '95600e57a1',\n      blogName: 'Vitalergy | TCM Gesundheitsblog f\u00fcr Bauch, Herz und Verstand'\n    };\n  <\/script>\n  <script type=\"application\/ld+json\">\n\t\t{\"@context\":\"https:\\\/\\\/schema.org\\\/\",\"@type\":\"Recipe\",\"name\":\"Maroni Creme Dessert mit Datteln\",\"image\":[\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/TCM-Rezept-Schnelle-Kastaniesuppe-Zutaten.png\",\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Maroni-Creme-mit-Datteln-ein-leichtes-Dessert.png\",\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/TCM-Rezept-Schnelle-Kastaniesuppe-Zutaten.png\",\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/TCM-Rezept-Schnelle-Kastaniesuppe-Vitalergy.png\",\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Maroni-Creme-mit-Datteln-ein-leichtes-Dessert-330x267.png\"],\"author\":{\"@type\":\"Person\",\"name\":\"Martina Tripold-Pratscher\"},\"datePublished\":\"2020-11-29\",\"description\":\"Maroni Creme mit Datteln ist eine gesundes, schnelles Dessert f\\u00fcr die Nerven. Du wirst es lieben, wenn du oft zu S\\u00fc\\u00dfgusto am Nachmittag neigst.\",\"recipeCuisine\":\"Schnelle K\\u00fcche\",\"prepTime\":\"P0DT0H8M0S\",\"cookTime\":\"P0DT0H0M0S\",\"totalTime\":\"P0DT0H8M0S\",\"recipeYield\":\"2 Portionen\",\"recipeCategory\":\"Kochrezepte nach TCM\",\"recipeIngredient\":[\"200 g vorgegarte Maroni,\",\"50  - 100 g Datteln,\",\"125 ml Obers\",\"2  Prisen gemahlen Kardamom\",\"etwas Wasser zum Einweichen der Datteln\",\"10  Himbeeren\",\"1 EL Kakaopulver nach Geschmack,\",\"2  Prisen Cylon Zimt\"],\"recipeInstructions\":[{\"@type\":\"HowToStep\",\"text\":\"Datteln klein schneiden. In einem Topf mit etwas Wasser kurz weichkochen. (Wenn du mehr Zeit hast, kannst du es in einem Gef\\u00e4ss mit warmem Wasser 1 Stunde einweichen.)\"},{\"@type\":\"HowToStep\",\"text\":\"Maroni und Gew\\u00fcrze in einen hohen Beh\\u00e4lter mit etwas Obers (oder vegan \\\/ Laktose frei: 2 EL Mandelmus p\\u00fcrieren.\"},{\"@type\":\"HowToStep\",\"text\":\"Danach die abgek\\u00fchlten Datteln dazugeben und mit p\\u00fcrieren.\"},{\"@type\":\"HowToStep\",\"text\":\"Den geschlagenen Obers unterr\\u00fchren und alles in Gl\\u00e4ser oder Sch\\u00fcsseln einf\\u00fcllen.Vorm Servieren mit frischem Obst wie Himbeeren und \\\/ oder Kakaopulver dekorieren und verfeinern.\"}],\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":\"5\",\"ratingCount\":\"5\"},\"video\":{\"@type\":\"VideoObject\",\"description\":\"Maroni Creme mit Datteln ist eine gesundes, schnelles Dessert f\\u00fcr die Nerven. Du wirst es lieben, wenn du oft zu S\\u00fc\\u00dfgusto am Nachmittag neigst.\",\"name\":\"Maroni Creme Dessert mit Datteln\",\"thumbnailUrl\":\"https:\\\/\\\/gelassen-vital.at\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Maroni-Creme-mit-Datteln-ein-leichtes-Dessert-330x267.png\",\"uploadDate\":\"2020-11-29\",\"embedUrl\":\"\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/f7EjHned9O0\"}}\n  <\/script>\n  <style>\n    .foodblogkitchen-toolkit--block.foodblogkitchen-toolkit--block {\n      --background: #fefcfc;\n      --background-contrast: #000000;\n      --secondary: #efefef;\n      --secondary-contrast: #000000;\n      --primary: #7ead2f;\n      --primary-contrast: #000000;\n      --primary-light: #D8EBB7;\n      --primary-light-contrast: #000000;\n      --primary-dark: #4C681C;\n  \n  \n      --border-radius: 15px;\n      --box-shadow: 0 1px 3px rgba(0, 0, 0, 0.12), 0 1px 2px rgba(0, 0, 0, 0.24);\n  \n      --border: 1px solid #7ead2f;\n  \n      --clock-url: url(data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSIyNCIgaGVpZ2h0PSIyNCIgdmlld0JveD0iMCAwIDI0IDI0IiBzdHJva2Utd2lkdGg9IjIiIHN0cm9rZT0iIzAwMDAwMCIgZmlsbD0ibm9uZSIgc3Ryb2tlLWxpbmVjYXA9InJvdW5kIiBzdHJva2UtbGluZWpvaW49InJvdW5kIj48cGF0aCBzdHJva2U9Im5vbmUiIGQ9Ik0wIDBoMjR2MjRIMHoiIGZpbGw9Im5vbmUiLz48Y2lyY2xlIGN4PSIxMiIgY3k9IjEyIiByPSI5IiAvPjxwb2x5bGluZSBwb2ludHM9IjEyIDcgMTIgMTIgMTUgMTUiIC8+PC9zdmc+);\n      --star-url: url(data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSIyNCIgaGVpZ2h0PSIyNCIgdmlld0JveD0iMCAwIDI0IDI0IiBmaWxsPSJub25lIiBzdHJva2U9IiM3ZWFkMmYiIHN0cm9rZS13aWR0aD0iMiIgc3Ryb2tlLWxpbmVjYXA9InJvdW5kIiBzdHJva2UtbGluZWpvaW49InJvdW5kIj48cG9seWdvbiBwb2ludHM9IjEyIDIgMTUuMDkgOC4yNiAyMiA5LjI3IDE3IDE0LjE0IDE4LjE4IDIxLjAyIDEyIDE3Ljc3IDUuODIgMjEuMDIgNyAxNC4xNCAyIDkuMjcgOC45MSA4LjI2IDEyIDIiPjwvcG9seWdvbj48L3N2Zz4=);\n      --star-filled-url: url(data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSIyNCIgaGVpZ2h0PSIyNCIgdmlld0JveD0iMCAwIDI0IDI0IiBmaWxsPSIjN2VhZDJmIiBzdHJva2U9IiM3ZWFkMmYiIHN0cm9rZS13aWR0aD0iMiIgc3Ryb2tlLWxpbmVjYXA9InJvdW5kIiBzdHJva2UtbGluZWpvaW49InJvdW5kIj48cG9seWdvbiBwb2ludHM9IjEyIDIgMTUuMDkgOC4yNiAyMiA5LjI3IDE3IDE0LjE0IDE4LjE4IDIxLjAyIDEyIDE3Ljc3IDUuODIgMjEuMDIgNyAxNC4xNCAyIDkuMjcgOC45MSA4LjI2IDEyIDIiPjwvcG9seWdvbj48L3N2Zz4=);\n      --star-half-filled-url: url(data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSIyNCIgaGVpZ2h0PSIyNCIgdmlld0JveD0iMCAwIDI0IDI0IiBmaWxsPSJ1cmwoI2hhbGZfZ3JhZCkiIHN0cm9rZT0iIzdlYWQyZiIgc3Ryb2tlLXdpZHRoPSIyIiBzdHJva2UtbGluZWNhcD0icm91bmQiIHN0cm9rZS1saW5lam9pbj0icm91bmQiPjxkZWZzPjxsaW5lYXJHcmFkaWVudCBpZD0iaGFsZl9ncmFkIj48c3RvcCBvZmZzZXQ9IjUwJSIgc3RvcC1jb2xvcj0iIzdlYWQyZiIvPjxzdG9wIG9mZnNldD0iNTAlIiBzdG9wLWNvbG9yPSJ0cmFuc3BhcmVudCIgc3RvcC1vcGFjaXR5PSIxIiAvPjwvbGluZWFyR3JhZGllbnQ+PC9kZWZzPjxwb2x5Z29uIHBvaW50cz0iMTIgMiAxNS4wOSA4LjI2IDIyIDkuMjcgMTcgMTQuMTQgMTguMTggMjEuMDIgMTIgMTcuNzcgNS44MiAyMS4wMiA3IDE0LjE0IDIgOS4yNyA4LjkxIDguMjYgMTIgMiI+PC9wb2x5Z29uPjwvc3ZnPg==);\n      --star-highlighted-url: url(data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSIyNCIgaGVpZ2h0PSIyNCIgdmlld0JveD0iMCAwIDI0IDI0IiBmaWxsPSIjNEM2ODFDIiBzdHJva2U9IiM0QzY4MUMiIHN0cm9rZS13aWR0aD0iMiIgc3Ryb2tlLWxpbmVjYXA9InJvdW5kIiBzdHJva2UtbGluZWpvaW49InJvdW5kIj48cG9seWdvbiBwb2ludHM9IjEyIDIgMTUuMDkgOC4yNiAyMiA5LjI3IDE3IDE0LjE0IDE4LjE4IDIxLjAyIDEyIDE3Ljc3IDUuODIgMjEuMDIgNyAxNC4xNCAyIDkuMjcgOC45MSA4LjI2IDEyIDIiPjwvcG9seWdvbj48L3N2Zz4=);\n      --instagram-url: url(data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzYiIGhlaWdodD0iMzYiIHZpZXdCb3g9IjAgMCAzNiAzNiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBmaWxsPSIjMDAwMDAwIj4gPHRpdGxlPklHIExvZ288L3RpdGxlPjxnIGZpbGwtcnVsZT0iZXZlbm9kZCI+PHBhdGggZD0iTTE4IDBjLTQuODg5IDAtNS41MDEuMDItNy40MjEuMTA4QzguNjYzLjE5NiA3LjM1NC41IDYuMjA5Ljk0NWE4LjgyMyA4LjgyMyAwIDAgMC0zLjE4OCAyLjA3NkE4LjgzIDguODMgMCAwIDAgLjk0NSA2LjIwOUMuNSA3LjM1NC4xOTUgOC42NjMuMTA4IDEwLjU4LjAyMSAxMi40OTkgMCAxMy4xMSAwIDE4cy4wMiA1LjUwMS4xMDggNy40MjFjLjA4OCAxLjkxNi4zOTIgMy4yMjUuODM3IDQuMzdhOC44MjMgOC44MjMgMCAwIDAgMi4wNzYgMy4xODhjMSAxIDIuMDA1IDEuNjE2IDMuMTg4IDIuMDc2IDEuMTQ1LjQ0NSAyLjQ1NC43NSA0LjM3LjgzNyAxLjkyLjA4NyAyLjUzMi4xMDggNy40MjEuMTA4czUuNTAxLS4wMiA3LjQyMS0uMTA4YzEuOTE2LS4wODggMy4yMjUtLjM5MiA0LjM3LS44MzdhOC44MjQgOC44MjQgMCAwIDAgMy4xODgtMi4wNzZjMS0xIDEuNjE2LTIuMDA1IDIuMDc2LTMuMTg4LjQ0NS0xLjE0NS43NS0yLjQ1NC44MzctNC4zNy4wODctMS45Mi4xMDgtMi41MzIuMTA4LTcuNDIxcy0uMDItNS41MDEtLjEwOC03LjQyMWMtLjA4OC0xLjkxNi0uMzkyLTMuMjI1LS44MzctNC4zN2E4LjgyNCA4LjgyNCAwIDAgMC0yLjA3Ni0zLjE4OEE4LjgzIDguODMgMCAwIDAgMjkuNzkxLjk0NUMyOC42NDYuNSAyNy4zMzcuMTk1IDI1LjQyLjEwOCAyMy41MDEuMDIxIDIyLjg5IDAgMTggMHptMCAzLjI0M2M0LjgwNiAwIDUuMzc2LjAxOSA3LjI3NC4xMDUgMS43NTUuMDggMi43MDguMzczIDMuMzQyLjYyLjg0LjMyNiAxLjQ0LjcxNyAyLjA3IDEuMzQ2LjYzLjYzIDEuMDIgMS4yMyAxLjM0NiAyLjA3LjI0Ny42MzQuNTQgMS41ODcuNjIgMy4zNDIuMDg2IDEuODk4LjEwNSAyLjQ2OC4xMDUgNy4yNzRzLS4wMTkgNS4zNzYtLjEwNSA3LjI3NGMtLjA4IDEuNzU1LS4zNzMgMi43MDgtLjYyIDMuMzQyYTUuNTc2IDUuNTc2IDAgMCAxLTEuMzQ2IDIuMDdjLS42My42My0xLjIzIDEuMDItMi4wNyAxLjM0Ni0uNjM0LjI0Ny0xLjU4Ny41NC0zLjM0Mi42Mi0xLjg5OC4wODYtMi40NjcuMTA1LTcuMjc0LjEwNXMtNS4zNzYtLjAxOS03LjI3NC0uMTA1Yy0xLjc1NS0uMDgtMi43MDgtLjM3My0zLjM0Mi0uNjJhNS41NzYgNS41NzYgMCAwIDEtMi4wNy0xLjM0NiA1LjU3NyA1LjU3NyAwIDAgMS0xLjM0Ni0yLjA3Yy0uMjQ3LS42MzQtLjU0LTEuNTg3LS42Mi0zLjM0Mi0uMDg2LTEuODk4LS4xMDUtMi40NjgtLjEwNS03LjI3NHMuMDE5LTUuMzc2LjEwNS03LjI3NGMuMDgtMS43NTUuMzczLTIuNzA4LjYyLTMuMzQyLjMyNi0uODQuNzE3LTEuNDQgMS4zNDYtMi4wNy42My0uNjMgMS4yMy0xLjAyIDIuMDctMS4zNDYuNjM0LS4yNDcgMS41ODctLjU0IDMuMzQyLS42MiAxLjg5OC0uMDg2IDIuNDY4LS4xMDUgNy4yNzQtLjEwNXoiLz48cGF0aCBkPSJNMTggMjQuMDA2YTYuMDA2IDYuMDA2IDAgMSAxIDAtMTIuMDEyIDYuMDA2IDYuMDA2IDAgMCAxIDAgMTIuMDEyem0wLTE1LjI1OGE5LjI1MiA5LjI1MiAwIDEgMCAwIDE4LjUwNCA5LjI1MiA5LjI1MiAwIDAgMCAwLTE4LjUwNHptMTEuOTQ0LS4xNjhhMi4xODcgMi4xODcgMCAxIDEtNC4zNzQgMCAyLjE4NyAyLjE4NyAwIDAgMSA0LjM3NCAwIi8+PC9nPjwvc3ZnPg==);\n    }\n  <\/style><\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:95%\">\n<h2 id=\"\" class=\"has-text-align-center wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#fcb900\" class=\"has-inline-color\"><\/mark><\/h2>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-black-color has-text-color has-small-font-size wp-block-paragraph\"><strong>Hinweise f\u00fcr Anf\u00e4nger der TCM-Ern\u00e4hrungslehre (auch 5 Elemente K\u00fcche genannt):<\/strong><br>Jede Speise oder jedes Getr\u00e4nk sollte m\u00f6glichst alle Geschmacksrichtung beinhalten. <\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-small-font-size wp-block-paragraph\">Das f\u00f6rdert am besten den harmonischen Fluss des Qi&#8217;s im K\u00f6rper &amp; im Geist.<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-small-font-size wp-block-paragraph\">Ebenso ist die Philosophie dahinter, dass die Zutaten &#8216;rund&#8217; schmecken im Mund. <\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-small-font-size wp-block-paragraph\">Harmonisch miteinander abgestimmt, das f\u00f6rdert die Bek\u00f6mmlichkeit. <\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-small-font-size wp-block-paragraph\">Und das Yin und Yang ist f\u00fcr den menschlichen Organismus am besten verf\u00fcgbar. <\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\"><strong>Die Abk\u00fcrzungen neben der Zutatenliste bedeuten:<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">H = Holz, steht f\u00fcr den sauren Geschmack &amp; repr\u00e4sentiert die Organe Leber\/Gallenblase<br>F = Feuer, steht f\u00fcr den bitteren Geschmack &amp; repr\u00e4sentiert die Organe Herz\/D\u00fcnndarm<br>E = Erde, steht f\u00fcr den s\u00fc\u00dfen Geschmack &amp; repr\u00e4sentiert die Organe Milz\/Magen<br>M = Metall, steht f\u00fcr den scharfen Geschmack &amp; repr\u00e4sentiert die Organe Lunge\/Dickdarm<br>W = Wasser, steht f\u00fcr den salzigen Geschmack &amp; repr\u00e4sentiert die Organe Niere\/Blase<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top is-image-fill has-text-color has-background has-link-color wp-elements-7588c744e49afb3add0f8f826885c8ec\" style=\"color:#fffdc7;background-color:#7ead2f;grid-template-columns:auto 32%\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group has-link-color wp-elements-fb2cece218d728427fc685e10f8c78fd is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<p class=\"has-white-color has-text-color wp-block-paragraph\">M\u00f6chtest deine Gesundheit selbst f\u00f6rdern und vor allem von der Basis weg aufbauen? Deine Mitte st\u00e4rken durch positive, mentale Einstellung und Ern\u00e4hrungstipps, die keinem Trend folgen, sondern nach deinem Bauchtypen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Ern\u00e4hrung, die deine St\u00e4rken aufbaut und deine Schw\u00e4chen nat\u00fcrlich ausgleicht?<\/p>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Du bist bereit, dich f\u00fcr dein ganzheitliches Wohlbefinden weiterzubilden und nachhaltiges Gesundheitswissen f\u00fcr den Alltag lernen? <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Starte beim Optimieren deines <strong>Koch- und Essverhaltens!<\/strong><\/h2>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\"><strong>Schau dir mal meine online Kursangebote durch:<\/strong><\/p>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\"><a href=\"https:\/\/gelassen-vital.at\/blog\/tcm-online-kochkurse-live\/\"><strong>\u2192<\/strong>  5 live abgehaltene online Kochkurse nach TCM<\/a>  zu wichtigen Themen<\/p>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\"><a href=\"http:\/\/go.vitalergy.at\/ddk-spring\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>\u2192<\/strong> 3-w\u00f6chiges online Gruppen Programm<\/a> zum Detoxen und Darm reinigen<\/p>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media lazyload\" style=\"background-image:inherit;background-position:50% 50%\" data-bg-image=\"url(https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-800x534.jpg)\"><img decoding=\"async\" width=\"800\" height=\"534\" data-src=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-800x534.jpg\" alt=\"\" class=\"wp-image-6304 size-full lazyload\" data-srcset=\"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-800x534.jpg 800w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-300x200.jpg 300w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-768x513.jpg 768w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-330x220.jpg 330w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen-1000x667.jpg 1000w, https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/10\/Martina-vortragen.jpg 1500w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/534;\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Maroni Creme mit Datteln ist eine gesundes, schnelles Dessert f\u00fcr die Nerven. Du wirst es lieben, wenn du oft zu S\u00fc\u00dfgusto am Nachmittag neigst.<\/p>\n","protected":false},"author":1,"featured_media":6627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"foodblogkitchen_pinterest_image_id":6627,"foodblogkitchen_pinterest_image_url":"https:\/\/gelassen-vital.at\/blog\/wp-content\/uploads\/2022\/11\/Maroni-Creme-mit-Datteln-ein-leichtes-Dessert.png","rating_1_votes":0,"rating_2_votes":0,"rating_3_votes":0,"rating_4_votes":0,"rating_5_votes":5,"rating_count":5,"average_rating":5,"footnotes":""},"categories":[38],"tags":[],"post_folder":[54],"class_list":["post-6619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-kochrezepte"],"_links":{"self":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/6619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/comments?post=6619"}],"version-history":[{"count":23,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/6619\/revisions"}],"predecessor-version":[{"id":6682,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/posts\/6619\/revisions\/6682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/media\/6627"}],"wp:attachment":[{"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/media?parent=6619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/categories?post=6619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/tags?post=6619"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/gelassen-vital.at\/blog\/wp-json\/wp\/v2\/post_folder?post=6619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}